{"id":532811,"date":"2026-07-15T12:29:20","date_gmt":"2026-07-15T16:29:20","guid":{"rendered":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/"},"modified":"2026-07-15T12:29:20","modified_gmt":"2026-07-15T16:29:20","slug":"citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference","status":"publish","type":"post","link":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/","title":{"rendered":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference"},"content":{"rendered":"<p><b>Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference<\/b><br \/>\n<!-- no image --><br \/>\n<br \/>\n<a href=\"https:\/\/www.queerty.com\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference-20260715\/\" class=\"autohyperlink\">www.queerty.com\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference-20260715\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference <a href=\"http:\/\/www.queerty.com\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference-20260715\/\" class=\"autohyperlink\">www.queerty.com\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference-20260715\/<\/a><\/p>\n","protected":false},"author":2466,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[108,109],"class_list":["post-532811","post","type-post","status-publish","format-standard","hentry","category-news","tag-gaynews","tag-lgbtnews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference - GAYFRIENDSCHAT.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference - GAYFRIENDSCHAT.com\" \/>\n<meta property=\"og:description\" content=\"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference www.queerty.com\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference-20260715\/\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"GAYFRIENDSCHAT.com\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T16:29:20+00:00\" \/>\n<meta name=\"author\" content=\"GayFriendschat.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gayfriendschat\" \/>\n<meta name=\"twitter:site\" content=\"@gayfriendschat\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GayFriendschat.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/\"},\"author\":{\"name\":\"GayFriendschat.com\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/person\\\/181913201d50f65b9bba7437f822a17f\"},\"headline\":\"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference\",\"datePublished\":\"2026-07-15T16:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/\"},\"wordCount\":35,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#organization\"},\"keywords\":[\"#gaynews\",\"#lgbtnews\"],\"articleSection\":[\"NEWS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/\",\"name\":\"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference - GAYFRIENDSCHAT.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#website\"},\"datePublished\":\"2026-07-15T16:29:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#website\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/\",\"name\":\"GAYFRIENDSCHAT.com\",\"description\":\"LGBT BLOG\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#organization\",\"name\":\"GayFriendsChat.com\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo.jpg\",\"width\":243,\"height\":96,\"caption\":\"GayFriendsChat.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gayfriendschat\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/person\\\/181913201d50f65b9bba7437f822a17f\",\"name\":\"GayFriendschat.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g\",\"caption\":\"GayFriendschat.com\"},\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/author\\\/gayfriendschat-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference - GAYFRIENDSCHAT.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/","og_locale":"en_US","og_type":"article","og_title":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference - GAYFRIENDSCHAT.com","og_description":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference www.queerty.com\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference-20260715\/","og_url":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/","og_site_name":"GAYFRIENDSCHAT.com","article_published_time":"2026-07-15T16:29:20+00:00","author":"GayFriendschat.com","twitter_card":"summary_large_image","twitter_creator":"@gayfriendschat","twitter_site":"@gayfriendschat","twitter_misc":{"Written by":"GayFriendschat.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/#article","isPartOf":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/"},"author":{"name":"GayFriendschat.com","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/person\/181913201d50f65b9bba7437f822a17f"},"headline":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference","datePublished":"2026-07-15T16:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/"},"wordCount":35,"commentCount":0,"publisher":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#organization"},"keywords":["#gaynews","#lgbtnews"],"articleSection":["NEWS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/","url":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/","name":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference - GAYFRIENDSCHAT.com","isPartOf":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#website"},"datePublished":"2026-07-15T16:29:20+00:00","breadcrumb":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/citizenry-suddenly-very-interested-in-municipal-recreation-after-park-official-wears-speedo-to-press-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gayfriendschat.com\/socialblog\/"},{"@type":"ListItem","position":2,"name":"Citizenry suddenly very interested in municipal recreation after park official wears Speedo to press conference"}]},{"@type":"WebSite","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#website","url":"https:\/\/www.gayfriendschat.com\/socialblog\/","name":"GAYFRIENDSCHAT.com","description":"LGBT BLOG","publisher":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gayfriendschat.com\/socialblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#organization","name":"GayFriendsChat.com","url":"https:\/\/www.gayfriendschat.com\/socialblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-content\/uploads\/2019\/01\/Logo.jpg","contentUrl":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-content\/uploads\/2019\/01\/Logo.jpg","width":243,"height":96,"caption":"GayFriendsChat.com"},"image":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gayfriendschat"]},{"@type":"Person","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/person\/181913201d50f65b9bba7437f822a17f","name":"GayFriendschat.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g","caption":"GayFriendschat.com"},"url":"https:\/\/www.gayfriendschat.com\/socialblog\/author\/gayfriendschat-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/posts\/532811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/users\/2466"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/comments?post=532811"}],"version-history":[{"count":0,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/posts\/532811\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/media?parent=532811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/categories?post=532811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/tags?post=532811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}