{"id":16596,"date":"2015-03-31T00:30:33","date_gmt":"2015-03-31T04:30:33","guid":{"rendered":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/"},"modified":"2015-03-31T00:30:33","modified_gmt":"2015-03-31T04:30:33","slug":"in-op-ed-indiana-governor-claims-new-law-not-discriminatory","status":"publish","type":"post","link":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/","title":{"rendered":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory"},"content":{"rendered":"<p><b>In Op-ed, Indiana Governor Claims New Law Not Discriminatory<\/b><br \/>\n<!--paging_filter--><\/p>\n<p>In a <em>Wall Street Journal<\/em> piece, Gov. Mike Pence says his state&#8217;s new &#8216;religious freedom&#8217; law is not a license to discriminate against LGBT peop.e<\/p>\n<p><a href=\"http:\/\/www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory\" target=\"_blank\">read more<\/a><\/p>\n<p>Trudy Ring<\/p>\n<p><a href=\"http:\/\/www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory\" class=\"autohyperlink\">www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Op-ed, Indiana Governor Claims New Law Not Discriminatory In a Wall Street Journal piece, Gov. Mike Pence says his state&#8217;s new &#8216;religious freedom&#8217; law is not a license to discriminate against LGBT peop.e read more Trudy Ring <a href=\"http:\/\/www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory\" class=\"autohyperlink\">www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory<\/a><\/p>\n","protected":false},"author":2466,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[],"class_list":["post-16596","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In Op-ed, Indiana Governor Claims New Law Not Discriminatory - GAYFRIENDSCHAT.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Op-ed, Indiana Governor Claims New Law Not Discriminatory - GAYFRIENDSCHAT.com\" \/>\n<meta property=\"og:description\" content=\"In Op-ed, Indiana Governor Claims New Law Not Discriminatory In a Wall Street Journal piece, Gov. Mike Pence says his state&#8217;s new &#8216;religious freedom&#8217; law is not a license to discriminate against LGBT peop.e read more Trudy Ring www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/\" \/>\n<meta property=\"og:site_name\" content=\"GAYFRIENDSCHAT.com\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-31T04:30:33+00:00\" \/>\n<meta name=\"author\" content=\"GayFriendschat.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gayfriendschat\" \/>\n<meta name=\"twitter:site\" content=\"@gayfriendschat\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GayFriendschat.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/\"},\"author\":{\"name\":\"GayFriendschat.com\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/person\\\/181913201d50f65b9bba7437f822a17f\"},\"headline\":\"In Op-ed, Indiana Governor Claims New Law Not Discriminatory\",\"datePublished\":\"2015-03-31T04:30:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/\"},\"wordCount\":55,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#organization\"},\"articleSection\":[\"NEWS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/\",\"name\":\"In Op-ed, Indiana Governor Claims New Law Not Discriminatory - GAYFRIENDSCHAT.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#website\"},\"datePublished\":\"2015-03-31T04:30:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In Op-ed, Indiana Governor Claims New Law Not Discriminatory\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#website\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/\",\"name\":\"GAYFRIENDSCHAT.com\",\"description\":\"LGBT BLOG\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#organization\",\"name\":\"GayFriendsChat.com\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Logo.jpg\",\"width\":243,\"height\":96,\"caption\":\"GayFriendsChat.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/gayfriendschat\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/#\\\/schema\\\/person\\\/181913201d50f65b9bba7437f822a17f\",\"name\":\"GayFriendschat.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g\",\"caption\":\"GayFriendschat.com\"},\"url\":\"https:\\\/\\\/www.gayfriendschat.com\\\/socialblog\\\/author\\\/gayfriendschat-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory - GAYFRIENDSCHAT.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/","og_locale":"en_US","og_type":"article","og_title":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory - GAYFRIENDSCHAT.com","og_description":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory In a Wall Street Journal piece, Gov. Mike Pence says his state&#8217;s new &#8216;religious freedom&#8217; law is not a license to discriminate against LGBT peop.e read more Trudy Ring www.advocate.com\/politics\/2015\/03\/30\/op-ed-indiana-governor-claims-new-law-not-discriminatory","og_url":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/","og_site_name":"GAYFRIENDSCHAT.com","article_published_time":"2015-03-31T04:30:33+00:00","author":"GayFriendschat.com","twitter_card":"summary_large_image","twitter_creator":"@gayfriendschat","twitter_site":"@gayfriendschat","twitter_misc":{"Written by":"GayFriendschat.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/#article","isPartOf":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/"},"author":{"name":"GayFriendschat.com","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/person\/181913201d50f65b9bba7437f822a17f"},"headline":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory","datePublished":"2015-03-31T04:30:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/"},"wordCount":55,"commentCount":0,"publisher":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#organization"},"articleSection":["NEWS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/","url":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/","name":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory - GAYFRIENDSCHAT.com","isPartOf":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#website"},"datePublished":"2015-03-31T04:30:33+00:00","breadcrumb":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/in-op-ed-indiana-governor-claims-new-law-not-discriminatory\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gayfriendschat.com\/socialblog\/"},{"@type":"ListItem","position":2,"name":"In Op-ed, Indiana Governor Claims New Law Not Discriminatory"}]},{"@type":"WebSite","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#website","url":"https:\/\/www.gayfriendschat.com\/socialblog\/","name":"GAYFRIENDSCHAT.com","description":"LGBT BLOG","publisher":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gayfriendschat.com\/socialblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#organization","name":"GayFriendsChat.com","url":"https:\/\/www.gayfriendschat.com\/socialblog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/logo\/image\/","url":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-content\/uploads\/2019\/01\/Logo.jpg","contentUrl":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-content\/uploads\/2019\/01\/Logo.jpg","width":243,"height":96,"caption":"GayFriendsChat.com"},"image":{"@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/gayfriendschat"]},{"@type":"Person","@id":"https:\/\/www.gayfriendschat.com\/socialblog\/#\/schema\/person\/181913201d50f65b9bba7437f822a17f","name":"GayFriendschat.com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42a0cb75ed5dd34c6dc3e0aa48adf030c1c38a2c9dc59146f4afdf18e4bdf1d4?s=96&d=blank&r=g","caption":"GayFriendschat.com"},"url":"https:\/\/www.gayfriendschat.com\/socialblog\/author\/gayfriendschat-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/posts\/16596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/users\/2466"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/comments?post=16596"}],"version-history":[{"count":0,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/posts\/16596\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/media?parent=16596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/categories?post=16596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gayfriendschat.com\/socialblog\/wp-json\/wp\/v2\/tags?post=16596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}